{"id":37589,"date":"2021-10-26T14:11:12","date_gmt":"2021-10-26T13:11:12","guid":{"rendered":"https://www.miltonandking.com/eu/?post_type=product&#038;p=37589"},"modified":"2026-02-17T04:49:19","modified_gmt":"2026-02-17T04:49:19","slug":"cotton-grass-wallpaper","status":"publish","type":"product","link":"https://www.miltonandking.eu/product/cotton-grass-wallpaper/","title":{"rendered":"Cotton Grass Wallpaper"},"content":{"rendered":"<p>In Anlehnung an die torfigen Moorfelder Schottlands und die offene Sicht auf lange Gräser mit flauschigen weißen Köpfen zeigt das Cotton Grass wallpaper diese schlanken Blüten, die miteinander tanzen. Auch als Moorwatte oder Hasenschwanz bekannt, ist das sich im Wind wiegende Baumwollgras ein wunderschöner Anblick. Der Künstler hat die Zartheit der Pflanze in diesem Tapetenmuster verkörpert und etwas wirklich Einzigartiges geschaffen, indem er handgezeichnete Linien in gedämpften Vintage-Farbtönen verwendete, die im Kontrast zu den modern Zickzacklinien am Horizont stehen.</p>\n<p>\n</p>","protected":false},"excerpt":{"rendered":"<p>In Anlehnung an die torfigen Moorfelder Schottlands und die offene Sicht auf lange Gräser mit flauschigen weißen Köpfen zeigt die Cotton Grass wallpaper diese schlanken Blüten, die miteinander tanzen. Das auch als Moorbaumwolle oder Hasenschwanz bekannte Baumwollgras, das sich im Wind wiegt, ist ein wunderschöner Anblick, und der Künstler hat die [...]</p>\n","protected":false},"featured_media":37606,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_cat":[31,2677],"product_tag":[754,762,771],"giftcard-category":[],"td_product_pattern":[2159],"td_product_room":[2153,2150,2152,2154,2156,2157,2151],"mak_product_category":[2910],"woo-feed-brand":[],"class_list":{"0":"post-37589","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-designer-wallpaper","7":"product_cat-prints-murals","8":"product_tag-best-kitchen-wallpaper","9":"product_tag-butterflies-moths-bees-caterpillars","10":"product_tag-dainty-vintage-florals","11":"pa_color-forest-green","12":"pa_color-indian-ink-blue","13":"pa_color-light-clay","14":"pa_color-moss-green","15":"pa_size-metre-sample","16":"pa_size-roll","17":"pa_size-sample","18":"td_product_style-cottage-wallpaper","19":"td_product_style-dark-academia-wallpaper","20":"td_product_color-blue-wallpaper","21":"td_product_color-green-wallpaper","22":"td_product_color-grey-wallpaper","23":"td_product_brand-hackney-co","24":"td_product_feature-domestic-commercial","25":"td_product_feature-good-light-fastness","26":"td_product_feature-paste-the-wall","27":"td_product_feature-straight-match","28":"td_product_feature-strippable","29":"td_product_feature-washable","30":"td_product_collection-wallpaper-republic","31":"td_product_pattern-floral-wallpaper","32":"td_product_room-bathroom-wallpaper","33":"td_product_room-bedroom-wallpaper","34":"td_product_room-dining-room-wallpaper","35":"td_product_room-hallway-wallpaper","36":"td_product_room-kitchen-wallpaper","37":"td_product_room-laundry-wallpaper","38":"td_product_room-living-room-wallpaper","39":"mak_product_category-non-woven-wallpaper","41":"first","42":"instock","43":"taxable","44":"shipping-taxable","45":"purchasable","46":"product-type-variable","47":"has-default-attributes"},"group_of_quantity":0,"min_quantity":0,"max_quantity":"","exclude_order_quantity_value_rules":"no","exclude_category_quantity_rules":"no","combine_variations":"no","acf":{"mak_additional_product_image":null,"td_product_shipping_time":"<p><strong>Auf Bestellung gefertigt.</strong> Lieferbar in 10-15 Tagen.</p>","td_product_sizing_info":"","td_product_roll_dimensions":"24\" (61.5cm) x 33ft (10.05m)","td_product_panel_set_dimensions":"","td_product_panel_dimensions":"","td_product_material_base":"Low Sheen Non-Woven","td_product_pattern_repeat":"11” (28cm)","td_product_pattern_match":"Straight Match","td_product_finish":"Pre-trimmed Butt Join","td_product_cleanability":"Washable","td_product_usage":"Domestic &amp; Commercial","td_product_adhesive":"","td_product_removal":"","td_product_lightfast_rating":"","mak_roomvo_length":"","mak_roomvo_width":"","embed_social_code":"","td_product_search_content_de":"Baumwollgras-Tapete - Die Baumwollgras-Tapete erinnert an die torfigen Moorfelder Schottlands und an die offene Landschaft mit langen Gräsern mit flauschigen weißen Köpfen und zeigt diese schlanken Blüten, die miteinander tanzen. Auch als Moorwatte oder Hasenschwanz bekannt, ist das sich im Wind wiegende Baumwollgras ein wunderschöner Anblick. Der Künstler hat die Zartheit der Pflanze in diesem fließenden Wiesentapetenmuster verkörpert und etwas wirklich Einzigartiges geschaffen, indem er handgezeichnete Linien in gedämpften Vintage-Farbtönen verwendet hat, die im Kontrast zu den modernen Zickzacklinien des Horizonts stehen.","td_product_search_content_fr":"Papier peint en coton - Faisant référence aux tourbières d'Écosse et aux panoramas ouverts de longues herbes aux têtes blanches duveteuses, le papier peint Cotton Grass représente ces fleurs élancées qui dansent entre elles. Également connue sous le nom de coton des tourbières ou de queue de lièvre, l'herbe de coton se balançant dans le vent est un spectacle magnifique et l'artiste a incarné la délicatesse de la plante dans ce motif de papier peint de prairie fluide, créant quelque chose de vraiment unique en utilisant un travail au trait dessiné à la main dans des teintes vintage atténuées contrastant avec le zig-zag moderne des lignes d'horizon.","td_product_search_content_it":"Carta da parati in cotone erba - Facendo riferimento ai campi di torba della Scozia e ai panorami aperti di lunghe erbe con soffici teste bianche, la carta da parati Cotton Grass ritrae queste esili fioriture che danzano tra loro. Conosciuta anche come cotone di torbiera o coda di lepre, l'erba di cotone che ondeggia al vento è uno spettacolo bellissimo da vedere e l'artista ha incarnato la delicatezza della pianta in questo motivo di carta da parati per prati fluidi, creando qualcosa di veramente unico grazie all'uso di linee disegnate a mano in tonalità vintage che contrastano con il moderno zig-zag delle linee dell'orizzonte.","td_product_search_content_es":"Papel pintado Cotton Grass - El papel pintado Cotton Grass, que evoca los campos de turba de Escocia y las vistas abiertas de largas hierbas con esponjosas cabezas blancas, retrata estas esbeltas flores bailando entre ellas. También conocida como algodón de los pantanos, o cola de liebre, la hierba de algodón mecida por el viento es un hermoso espectáculo para la vista y el artista ha plasmado la delicadeza de la planta en este patrón de papel pintado de pradera fluida creando algo verdaderamente único mediante el uso de líneas dibujadas a mano en tonos vintage que contrastan con el moderno zig-zag de las líneas del horizonte.","mak_product_sibling_non_woven":null,"mak_product_sibling_vinyl":null,"td_product_additional_information":"Auf Milton &amp; King haben wir eine riesige Auswahl an Designertapeten für Sie, egal ob Sie Ihren Flur, Ihr Wohnzimmer, Ihr Schlafzimmer oder Ihr Esszimmer dekorieren, wir haben eine Tapete, die zu Ihrem Stil und Ihrem Budget passt! Mit mehr als 500 Tapeten haben wir bestimmt die Tapete, nach der Sie suchen.\r\n<blockquote>\r\n<blockquote>\r\n<h5><strong>Vorteile der Vliestapete</strong>\r\nDie benutzerfreundlichste Tapete auf dem Markt.</h5>\r\n</blockquote>\r\n</blockquote>\r\n<ul>\r\n \t<li>Sie stammen aus FSC-zertifizierten Wäldern und werden mit ink auf Wasserbasis gedruckt. Milton &amp; King Die Tapeten des Unternehmens sind von höchster Qualität, umweltfreundlich und zu 100 % vinylfrei.</li>\r\n \t<li>Atmungsaktiv - Diese hochwertigen Tapeten sind atmungsaktiv, was ihnen hilft, Schimmel und Mehltau standzuhalten. Daher sind sie perfekt für die Dekoration von Badezimmern, Küchen und Wäschereien geeignet.</li>\r\n \t<li>Paste-The-Wall - Hergestellt sowohl aus natural als auch aus nicht porösen synthetischen Fasern. Diese Vliestapeten nehmen keine Feuchtigkeit aus dem Kleister auf. Tragen Sie den Kleister einfach direkt auf die Wand auf. Die Tapete dehnt sich nicht aus und zieht sich nicht zusammen, so dass keine Buchungszeit erforderlich ist.</li>\r\n \t<li>Die Tapetenrollen sind so präzise verarbeitet, dass sie sich nicht überlappen. Das bedeutet, dass die Bahnen einfach aneinander stoßen, was die Montage erleichtert.</li>\r\n \t<li>Reinigungsfähig - Schmutz, Staub und andere Verschmutzungen können einfach mit einem feuchten Tuch und Seifenwasser gereinigt werden.</li>\r\n \t<li>Strapazierfähig - Unsere Designertapeten sind außerdem sehr strapazierfähig und reißfest. Dies ist ein großer Vorteil, da die Tapeten bei der Anbringung oder Entfernung nicht reißen.</li>\r\n \t<li>Leicht zu entfernen - Sobald sie vollständig getrocknet sind, lassen sich Vliestapeten leicht abziehen. Sie sollten sich in full Bahnen ablösen lassen, ohne dass der gefürchtete Dampfstrahler oder Wasser benötigt wird. Ohne die Wände bei der Entfernung zu beschädigen</li>\r\n \t<li>Rollengröße - 24\" breit x 33' lang. Unsere Rollen sind das Äquivalent zu einer US-Doppelrolle und bieten 65 Quadratfuß pro Rolle.</li>\r\n</ul>","td_product_certifications":"<h5><strong>Diese Tapete hat die folgenden Brand- und Entflammbarkeitsklassifizierungen erhalten.</strong></h5>\r\n<strong>Nord-Amerika</strong>\r\n&quot;Klasse A&quot; für ASTM-Bezeichnung E84-15a. Vergleichbar mit UL 723, ANSI/NFPA No. 255 &amp; UBC No. 8-1.\r\n<strong>Zitierte Bauvorschriften:</strong>\r\nNational Fire Protection Association, ANSI/NFPA Nr. 101, \"Life Safety Code\". International Building Code, Kapitel 8, Innenausbau, Abschnitt 803.\r\n\r\n<strong>Australien und Neuseeland</strong>\r\n\"Gruppe 1\" für AS/NZS-Normen: AS/NZS 3837:1998\r\n<em>Die australische Bauordnung (BCA)</em>\r\n\r\nBitte <a href=\"https://www.miltonandking.eu/de/contact-us/\">Kontakt</a> um eine Kopie der Brandschutzbescheinigungen und Prüfberichte anzufordern.","mak_product_instructions":null,"td_product_vinyl_content":"","td_product_vinyl_pattern_repeat":"","td_product_vinyl_pattern_match":"","td_product_vinyl_features":[]},"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.2 (Yoast SEO v27.2) - https://yoast.com/product/yoast-seo-premium-wordpress/ -->\n<title>Cotton Grass Wallpaper - Zierliche Blumentapete - Milton &amp; King EU</title>\n<meta name=\"description\" content=\"Cotton Grass ist eine wunderschöne Tapete von Hackney &amp; Co. mit einem zarten Gras- und Blumenmuster. Kaufen Sie Tapeten für Ihr Zuhause.\">\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\">\n<link rel=\"canonical\" href=\"https://www.miltonandking.eu/de/product/cotton-grass-wallpaper/\">\n<meta property=\"og:locale\" content=\"en_GB\">\n<meta property=\"og:type\" content=\"article\">\n<meta property=\"og:title\" content=\"Cotton Grass Wallpaper\">\n<meta property=\"og:description\" content=\"In Anspielung auf die torfigen Moorfelder Schottlands und die offene Landschaft mit langen Gräsern mit flauschigen weißen Köpfen porträtiert die Cotton Grass wallpaper diese schlanken\">\n<meta property=\"og:url\" content=\"https://www.miltonandking.eu/de/product/cotton-grass-wallpaper/\">\n<meta property=\"og:site_name\" content=\"Milton &amp; King Europa\">\n<meta property=\"article:publisher\" content=\"https://www.facebook.com/miltonandking/\">\n<meta property=\"article:modified_time\" content=\"2026-02-17T04:49:19+00:00\">\n<meta property=\"og:image\" content=\"https://www.miltonandking.eu/wp-content/uploads/2021/10/Wallpaper-Hackney-WR471HC-Cotton-Grass-Moss-Green-1.jpg\">\n\t<meta property=\"og:image:width\" content=\"1100\">\n\t<meta property=\"og:image:height\" content=\"1320\">\n\t<meta property=\"og:image:type\" content=\"image/jpeg\">\n<meta name=\"twitter:card\" content=\"summary_large_image\">\n<meta name=\"twitter:site\" content=\"@miltonandking\">\n<script type=\"application/ld+json\" class=\"yoast-schema-graph\" data-wg-notranslate=\"\">{\"@context\":\"https://schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https://www.miltonandking.eu/product/cotton-grass-wallpaper/\",\"url\":\"https://www.miltonandking.eu/product/cotton-grass-wallpaper/\",\"name\":\"Cotton Grass Wallpaper • Dainty Floral Wallpaper • Milton & King EU\",\"isPartOf\":{\"@id\":\"https://www.miltonandking.eu/#website\"},\"primaryImageOfPage\":{\"@id\":\"https://www.miltonandking.eu/product/cotton-grass-wallpaper/#primaryimage\"},\"image\":{\"@id\":\"https://www.miltonandking.eu/product/cotton-grass-wallpaper/#primaryimage\"},\"thumbnailUrl\":\"https://www.miltonandking.eu/wp-content/uploads/2021/10/Wallpaper-Hackney-WR471HC-Cotton-Grass-Moss-Green-1.jpg\",\"datePublished\":\"2021-10-26T13:11:12+00:00\",\"dateModified\":\"2026-02-17T04:49:19+00:00\",\"description\":\"Cotton Grass is a beautiful wallpaper by Hackney & Co. featuring a delicate grass and floral pattern. Shop wallpaper for your home.\",\"breadcrumb\":{\"@id\":\"https://www.miltonandking.eu/product/cotton-grass-wallpaper/#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https://www.miltonandking.eu/product/cotton-grass-wallpaper/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https://www.miltonandking.eu/product/cotton-grass-wallpaper/#primaryimage\",\"url\":\"https://www.miltonandking.eu/wp-content/uploads/2021/10/Wallpaper-Hackney-WR471HC-Cotton-Grass-Moss-Green-1.jpg\",\"contentUrl\":\"https://www.miltonandking.eu/wp-content/uploads/2021/10/Wallpaper-Hackney-WR471HC-Cotton-Grass-Moss-Green-1.jpg\",\"width\":1100,\"height\":1320,\"caption\":\"Cotton Grass Wallpaper • Hackney & Co. • Moss Green • Swatch\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https://www.miltonandking.eu/product/cotton-grass-wallpaper/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https://www.miltonandking.eu/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https://www.miltonandking.eu/shop/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Designer Wallpaper\",\"item\":\"https://www.miltonandking.eu/product-category/designer-wallpaper/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Cotton Grass Wallpaper\"}]},{\"@type\":\"WebSite\",\"@id\":\"https://www.miltonandking.eu/#website\",\"url\":\"https://www.miltonandking.eu/\",\"name\":\"Milton &amp; King Europe\",\"description\":\"Your Vision, Our Craftsmanship.\",\"publisher\":{\"@id\":\"https://www.miltonandking.eu/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https://www.miltonandking.eu/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https://www.miltonandking.eu/#organization\",\"name\":\"Milton & King Europe\",\"url\":\"https://www.miltonandking.eu/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https://www.miltonandking.eu/#/schema/logo/image/\",\"url\":\"https://www.miltonandking.eu/wp-content/uploads/2018/12/logo.svg\",\"contentUrl\":\"https://www.miltonandking.eu/wp-content/uploads/2018/12/logo.svg\",\"width\":355,\"height\":52,\"caption\":\"Milton & King Europe\"},\"image\":{\"@id\":\"https://www.miltonandking.eu/#/schema/logo/image/\"},\"sameAs\":[\"https://www.facebook.com/miltonandking/\",\"https://x.com/miltonandking\",\"https://www.instagram.com/miltonandking/\",\"https://www.linkedin.com/company/18134551\",\"https://www.pinterest.com.au/miltonandking/\",\"https://www.youtube.com/channel/UCaReSxEnBoJBjEouXGK66HA\"]}]}</script>\n<meta property=\"product:brand\" content=\"Hackney &amp; Co\">\n<meta property=\"og:availability\" content=\"instock\">\n<meta property=\"product:availability\" content=\"instock\">\n<meta property=\"product:retailer_item_id\" content=\"HC104\">\n<meta property=\"product:condition\" content=\"new\">\n<!-- / Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Cotton Grass Wallpaper • Dainty Floral Wallpaper • Milton & King EU","description":"Cotton Grass ist eine wunderschöne Tapete von Hackney & Co. mit einem zarten Gras- und Blumenmuster. Kaufen Sie Tapeten für Ihr Zuhause.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https://www.miltonandking.eu/product/cotton-grass-wallpaper/","og_locale":"en_GB","og_type":"article","og_title":"Cotton Grass Wallpaper","og_description":"Referencing the peaty bog fields of Scotland and open vistas of long grasses with fluffy white heads, the Cotton Grass wallpaper portrays these slender","og_url":"https://www.miltonandking.eu/product/cotton-grass-wallpaper/","og_site_name":"Milton &amp; King Europe","article_publisher":"https://www.facebook.com/miltonandking/","article_modified_time":"2026-02-17T04:49:19+00:00","og_image":[{"width":1100,"height":1320,"url":"https://www.miltonandking.eu/de/wp-content/uploads/2021/10/Wallpaper-Hackney-WR471HC-Cotton-Grass-Moss-Green-1.jpg","type":"image/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@miltonandking","schema":{"@context":"https://schema.org","@graph":[{"@type":"WebPage","@id":"https://www.miltonandking.eu/product/cotton-grass-wallpaper/","url":"https://www.miltonandking.eu/de/product/cotton-grass-wallpaper/","name":"Cotton Grass Wallpaper • Dainty Floral Wallpaper • Milton & King EU","isPartOf":{"@id":"https://www.miltonandking.eu/#website"},"primaryImageOfPage":{"@id":"https://www.miltonandking.eu/product/cotton-grass-wallpaper/#primaryimage"},"image":{"@id":"https://www.miltonandking.eu/product/cotton-grass-wallpaper/#primaryimage"},"thumbnailUrl":"https://www.miltonandking.eu/wp-content/uploads/2021/10/Wallpaper-Hackney-WR471HC-Cotton-Grass-Moss-Green-1.jpg","datePublished":"2021-10-26T13:11:12+00:00","dateModified":"2026-02-17T04:49:19+00:00","description":"Cotton Grass ist eine wunderschöne Tapete von Hackney & Co. mit einem zarten Gras- und Blumenmuster. Kaufen Sie Tapeten für Ihr Zuhause.","breadcrumb":{"@id":"https://www.miltonandking.eu/product/cotton-grass-wallpaper/#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https://www.miltonandking.eu/product/cotton-grass-wallpaper/"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https://www.miltonandking.eu/product/cotton-grass-wallpaper/#primaryimage","url":"https://www.miltonandking.eu/de/wp-content/uploads/2021/10/Wallpaper-Hackney-WR471HC-Cotton-Grass-Moss-Green-1.jpg","contentUrl":"https://www.miltonandking.eu/wp-content/uploads/2021/10/Wallpaper-Hackney-WR471HC-Cotton-Grass-Moss-Green-1.jpg","width":1100,"height":1320,"caption":"Cotton Grass Wallpaper • Hackney & Co. • Moss Green • Swatch"},{"@type":"BreadcrumbList","@id":"https://www.miltonandking.eu/product/cotton-grass-wallpaper/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https://www.miltonandking.eu/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https://www.miltonandking.eu/shop/"},{"@type":"ListItem","position":3,"name":"Designer Wallpaper","item":"https://www.miltonandking.eu/product-category/designer-wallpaper/"},{"@type":"ListItem","position":4,"name":"Cotton Grass Wallpaper"}]},{"@type":"WebSite","@id":"https://www.miltonandking.eu/#website","url":"https://www.miltonandking.eu/de/","name":"Milton &amp; King Europe","description":"Ihre Vision, unsere Kunstfertigkeit.","publisher":{"@id":"https://www.miltonandking.eu/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https://www.miltonandking.eu/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https://www.miltonandking.eu/#organization","name":"Milton & King Europe","url":"https://www.miltonandking.eu/de/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https://www.miltonandking.eu/#/schema/logo/image/","url":"https://www.miltonandking.eu/de/wp-content/uploads/2018/12/logo.svg","contentUrl":"https://www.miltonandking.eu/wp-content/uploads/2018/12/logo.svg","width":355,"height":52,"caption":"Milton & King Europe"},"image":{"@id":"https://www.miltonandking.eu/#/schema/logo/image/"},"sameAs":["https://www.facebook.com/miltonandking/","https://x.com/miltonandking","https://www.instagram.com/miltonandking/","https://www.linkedin.com/company/18134551","https://www.pinterest.com.au/miltonandking/","https://www.youtube.com/channel/UCaReSxEnBoJBjEouXGK66HA"]}]},"product_brand":"Hackney &amp; Co","og_availability":"instock","product_availability":"instock","product_retailer_item_id":"HC104","product_condition":"new"},"_links":{"self":[{"href":"https://www.miltonandking.eu/wp-json/wp/v2/product/37589","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https://www.miltonandking.eu/wp-json/wp/v2/product"}],"about":[{"href":"https://www.miltonandking.eu/wp-json/wp/v2/types/product"}],"replies":[{"embeddable":true,"href":"https://www.miltonandking.eu/wp-json/wp/v2/comments?post=37589"}],"wp:featuredmedia":[{"embeddable":true,"href":"https://www.miltonandking.eu/wp-json/wp/v2/media/37606"}],"wp:attachment":[{"href":"https://www.miltonandking.eu/wp-json/wp/v2/media?parent=37589"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https://www.miltonandking.eu/wp-json/wp/v2/product_cat?post=37589"},{"taxonomy":"product_tag","embeddable":true,"href":"https://www.miltonandking.eu/wp-json/wp/v2/product_tag?post=37589"},{"taxonomy":"giftcard-category","embeddable":true,"href":"https://www.miltonandking.eu/wp-json/wp/v2/giftcard-category?post=37589"},{"taxonomy":"td_product_pattern","embeddable":true,"href":"https://www.miltonandking.eu/wp-json/wp/v2/td_product_pattern?post=37589"},{"taxonomy":"td_product_room","embeddable":true,"href":"https://www.miltonandking.eu/wp-json/wp/v2/td_product_room?post=37589"},{"taxonomy":"mak_product_category","embeddable":true,"href":"https://www.miltonandking.eu/wp-json/wp/v2/mak_product_category?post=37589"},{"taxonomy":"woo-feed-brand","embeddable":true,"href":"https://www.miltonandking.eu/wp-json/wp/v2/woo-feed-brand?post=37589"}],"curies":[{"name":"wp","href":"https://api.w.org/{rel}","templated":true}]}}